{"id":250542,"date":"2026-07-27T11:49:02","date_gmt":"2026-07-27T09:49:02","guid":{"rendered":"https:\/\/www.tendenzeshabbychic.it\/prodotto\/flocon-de-noel-rouge-antico-natale-avec-le-pere-noel-30-cm\/"},"modified":"2026-07-21T11:49:02","modified_gmt":"2026-07-21T09:49:02","slug":"flocon-de-noel-rouge-antico-natale-avec-le-pere-noel-30-cm","status":"publish","type":"product","link":"https:\/\/www.tendenzeshabbychic.it\/fr\/produit\/flocon-de-noel-rouge-antico-natale-avec-le-pere-noel-30-cm\/","title":{"rendered":"Flocon de No\u00ebl rouge \u00ab Antico Natale \u00bb avec le P\u00e8re No\u00ebl, 30 cm"},"content":{"rendered":"<p>Noeud de la collection \u00ab Antico Natale \u00bb, fabriqu\u00e9 artisanalement en Italie dans un boucl\u00e9 rouge tout doux. Le grand n\u0153ud sup\u00e9rieur encadre un tambourin rond orn\u00e9 d&rsquo;un imprim\u00e9 vintage repr\u00e9sentant le P\u00e8re No\u00ebl, agr\u00e9ment\u00e9 de baies rouges brillantes, de petites branches vertes, de d\u00e9tails dor\u00e9s et de longs rubans assortis. <\/p>\n<p>Une d\u00e9coration de No\u00ebl spectaculaire, id\u00e9ale pour mettre en valeur une porte, un mur ou un coin d\u00e9di\u00e9 aux f\u00eates. La richesse de ses d\u00e9tails et sa couleur rouge chaleureuse en font \u00e9galement une id\u00e9e de cadeau raffin\u00e9e. <\/p>\n<ul>\n<li>Boucl\u00e9 rouge \u00e0 la texture douce et \u00e9paisse<\/li>\n<li>Grand n\u0153ud avec de longs rubans pendants<\/li>\n<li>Tambourin orn\u00e9 d&rsquo;une illustration vintage du P\u00e8re No\u00ebl<\/li>\n<li>D\u00e9cor compos\u00e9 de baies, de petites branches vertes et de d\u00e9tails dor\u00e9s<\/li>\n<li>Fabrication artisanale italienne Madame Fiocc\u00f2<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>\u00ab Fiocc\u00f2 Antico Natale \u00bb en boucl\u00e9 rouge, orn\u00e9 d&rsquo;un grand n\u0153ud, d&rsquo;un tambourin du P\u00e8re No\u00ebl, de baies, de brindilles dor\u00e9es et de longs rubans. Id\u00e9e cadeau. <\/p>\n<p><strong>Dimensions<\/strong>:<br \/>\n, H 30 cm<\/p>\n","protected":false},"featured_media":250548,"comment_status":"open","ping_status":"closed","template":"","meta":{"_joinchat":[]},"pwb-brand":[3435],"product_brand":[],"product_cat":[3599,1503],"product_tag":[3295,1300,1394,1296,1298],"class_list":["post-250542","product","type-product","status-publish","has-post-thumbnail","pwb-brand-madame-fiocco","product_cat-decorations-de-noel-shabby-chic-peres-noel-rennes-et-decorations","product_cat-noel","product_tag-pere-noel","product_tag-fatto-a-mano-fr","product_tag-fleche","product_tag-idee-de-cadeau","product_tag-made-in-italy-fr","first","outofstock","taxable","shipping-taxable","purchasable","product-type-simple"],"brands":[{"id":3435,"name":"Madame Fiocc\u00f2","slug":"madame-fiocco"}],"_links":{"self":[{"href":"https:\/\/www.tendenzeshabbychic.it\/fr\/wp-json\/wp\/v2\/product\/250542","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tendenzeshabbychic.it\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.tendenzeshabbychic.it\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tendenzeshabbychic.it\/fr\/wp-json\/wp\/v2\/comments?post=250542"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tendenzeshabbychic.it\/fr\/wp-json\/wp\/v2\/media\/250548"}],"wp:attachment":[{"href":"https:\/\/www.tendenzeshabbychic.it\/fr\/wp-json\/wp\/v2\/media?parent=250542"}],"wp:term":[{"taxonomy":"pwb-brand","embeddable":true,"href":"https:\/\/www.tendenzeshabbychic.it\/fr\/wp-json\/wp\/v2\/pwb-brand?post=250542"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.tendenzeshabbychic.it\/fr\/wp-json\/wp\/v2\/product_brand?post=250542"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.tendenzeshabbychic.it\/fr\/wp-json\/wp\/v2\/product_cat?post=250542"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.tendenzeshabbychic.it\/fr\/wp-json\/wp\/v2\/product_tag?post=250542"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}