{"id":223192,"date":"2026-01-20T10:00:47","date_gmt":"2026-01-20T09:00:47","guid":{"rendered":"https:\/\/www.tendenzeshabbychic.it\/prodotto\/nuvole-di-stoffa-camino-de-mesa-mariposa-50x150\/"},"modified":"2026-01-29T20:52:06","modified_gmt":"2026-01-29T19:52:06","slug":"nuvole-di-stoffa-camino-de-mesa-mariposa-50x150","status":"publish","type":"product","link":"https:\/\/www.tendenzeshabbychic.it\/es\/producto\/nuvole-di-stoffa-camino-de-mesa-mariposa-50x150\/","title":{"rendered":"Nuvole di Stoffa Camino de mesa Mariposa 50&#215;150"},"content":{"rendered":"<p>El Camino de <strong>mesa Fiorir\u00e0 Farfalla<\/strong> de Nuvole di Stoffa transforma incluso la mesa de todos los d\u00edas en una elegante mise en place. Fabricado en <strong>algod\u00f3n<\/strong>, combina una brillante base marfil con un delicado estampado de <strong>peon\u00edas empolvadas<\/strong> y detalles rom\u00e1nticos, enmarcados por adornos cl\u00e1sicos en las esquinas. Los bordes rosa empolvado, con micropuntos tono sobre tono, enmarcan el Camino de mesa con discreci\u00f3n y estilo. Perfecto sobre una mesa, aparador o consola, solo o con un centro de flores y velas.   <\/p>\n<ul>\n<li>Algod\u00f3n agradable y pr\u00e1ctico<\/li>\n<li>Estampado Fiorir\u00e0 en tonos empolvados<\/li>\n<li>Marco decorativo efecto encaje<\/li>\n<li>Cenefa geom\u00e9trica elegante y f\u00e1cil de combinar<\/li>\n<li>Ideal para mesa y consola<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Camino de mesa de algod\u00f3n de la colecci\u00f3n <strong>Fiorir\u00e0<\/strong>, sobre una base de color marfil con un rom\u00e1ntico estampado de <strong>peon\u00edas rosa<\/strong> empolvado y delicados detalles de \u00abMariposa\u00bb. Elegante marco con adornos de efecto encaje en las esquinas y bordes rosa empolvado con micro motivos geom\u00e9tricos: un toque refinado que da inmediatamente a la mesa un aspecto m\u00e1s pulido. <\/p>\n<p><strong>Dimensiones<\/strong><br \/>\nDimensiones <strong>50 x 150 cm.<\/strong><\/p>\n","protected":false},"featured_media":223189,"comment_status":"open","ping_status":"closed","template":"","meta":{"_joinchat":[]},"pwb-brand":[2090],"product_brand":[],"product_cat":[2373,2377],"product_tag":[3402,2164],"class_list":["post-223192","product","type-product","status-publish","has-post-thumbnail","pwb-brand-nuvole-di-stoffa-es","product_cat-camino-de-mesa","product_cat-la-mesa","product_tag-colleccion-fiorira","product_tag-edicion-limitada","first","outofstock","taxable","shipping-taxable","purchasable","product-type-simple"],"brands":[{"id":2090,"name":"Nuvole di Stoffa","slug":"nuvole-di-stoffa-es"}],"_links":{"self":[{"href":"https:\/\/www.tendenzeshabbychic.it\/es\/wp-json\/wp\/v2\/product\/223192","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tendenzeshabbychic.it\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.tendenzeshabbychic.it\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tendenzeshabbychic.it\/es\/wp-json\/wp\/v2\/comments?post=223192"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tendenzeshabbychic.it\/es\/wp-json\/wp\/v2\/media\/223189"}],"wp:attachment":[{"href":"https:\/\/www.tendenzeshabbychic.it\/es\/wp-json\/wp\/v2\/media?parent=223192"}],"wp:term":[{"taxonomy":"pwb-brand","embeddable":true,"href":"https:\/\/www.tendenzeshabbychic.it\/es\/wp-json\/wp\/v2\/pwb-brand?post=223192"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.tendenzeshabbychic.it\/es\/wp-json\/wp\/v2\/product_brand?post=223192"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.tendenzeshabbychic.it\/es\/wp-json\/wp\/v2\/product_cat?post=223192"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.tendenzeshabbychic.it\/es\/wp-json\/wp\/v2\/product_tag?post=223192"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}