{"id":173299,"date":"2025-01-24T09:07:53","date_gmt":"2025-01-24T08:07:53","guid":{"rendered":"https:\/\/www.tendenzeshabbychic.it\/prodotto\/blanc-mariclo-decoracion-gallina-con-corazon-desmontable-18-cm\/"},"modified":"2025-01-08T03:07:53","modified_gmt":"2025-01-08T02:07:53","slug":"blanc-mariclo-decoracion-gallina-con-corazon-desmontable-18-cm","status":"publish","type":"product","link":"https:\/\/www.tendenzeshabbychic.it\/es\/producto\/blanc-mariclo-decoracion-gallina-con-corazon-desmontable-18-cm\/","title":{"rendered":"Blanc Maricl\u00f2 Decoraci\u00f3n Gallina con Coraz\u00f3n Desmontable 18 cm"},"content":{"rendered":"<p>Esta encantadora decoraci\u00f3n Blanc Maricl\u00f2, parte de la colecci\u00f3n Pasqua in Festa, es perfecta para darle un toque r\u00fastico y cari\u00f1oso a tu ambiente. Fabricado en madera de mango, el pollo presenta detalles \u00fanicos como el coraz\u00f3n blanco extra\u00edble y un refinado lazo de cuerda natural con peque\u00f1as cuentas decorativas. Ideal para completar tu mesa de Pascua o para a\u00f1adir un elemento country chic a tu sal\u00f3n, cocina o aparador. Su dise\u00f1o sencillo pero elegante se presta para combinarlo con flores, velas y otros complementos decorativos para crear un ambiente acogedor y armonioso. <\/p>\n<ul>\n<li><strong>Material natural:<\/strong> hecho de madera de mango resistente y duradera.<\/li>\n<li><strong>Dise\u00f1o cari\u00f1oso:<\/strong> coraz\u00f3n blanco extra\u00edble y detalles de cuerda para darle un toque especial.<\/li>\n<li><strong>Tama\u00f1o compacto:<\/strong> \ud83d\udccf 16 x 2 x 18 cm, perfecto para cualquier espacio.<\/li>\n<li><strong>Estilo vers\u00e1til:<\/strong> adecuado tanto para decoraciones de Pascua como para un ambiente country chic durante todo el a\u00f1o.<\/li>\n<li><strong>Artesan\u00eda:<\/strong> detalles que realzan la singularidad del producto.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Fascinante decoraci\u00f3n en madera de mango de la colecci\u00f3n Pasqua in Festa. La gallina r\u00fastica est\u00e1 adornada con un coraz\u00f3n blanco extra\u00edble y un lazo de cuerda natural. \ud83d\udccf 16 x 2 x 18 cm. <\/p>\n","protected":false},"featured_media":169790,"comment_status":"open","ping_status":"closed","template":"","meta":{"_joinchat":[]},"pwb-brand":[2076],"product_brand":[],"product_cat":[2369,2396],"product_tag":[2202,2283,3286],"class_list":["post-173299","product","type-product","status-publish","has-post-thumbnail","pwb-brand-blanc-mariclo-es","product_cat-pascua","product_cat-objetos","product_tag-gallinas","product_tag-idea-de-regalo","product_tag-ventas","first","outofstock","sale","taxable","shipping-taxable","purchasable","product-type-simple"],"brands":[{"id":2076,"name":"Blanc Mariclo","slug":"blanc-mariclo-es"}],"_links":{"self":[{"href":"https:\/\/www.tendenzeshabbychic.it\/es\/wp-json\/wp\/v2\/product\/173299","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tendenzeshabbychic.it\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.tendenzeshabbychic.it\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tendenzeshabbychic.it\/es\/wp-json\/wp\/v2\/comments?post=173299"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tendenzeshabbychic.it\/es\/wp-json\/wp\/v2\/media\/169790"}],"wp:attachment":[{"href":"https:\/\/www.tendenzeshabbychic.it\/es\/wp-json\/wp\/v2\/media?parent=173299"}],"wp:term":[{"taxonomy":"pwb-brand","embeddable":true,"href":"https:\/\/www.tendenzeshabbychic.it\/es\/wp-json\/wp\/v2\/pwb-brand?post=173299"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.tendenzeshabbychic.it\/es\/wp-json\/wp\/v2\/product_brand?post=173299"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.tendenzeshabbychic.it\/es\/wp-json\/wp\/v2\/product_cat?post=173299"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.tendenzeshabbychic.it\/es\/wp-json\/wp\/v2\/product_tag?post=173299"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}